{"id":74488,"date":"2025-03-04T20:53:18","date_gmt":"2025-03-04T20:53:18","guid":{"rendered":"https:\/\/soleyantonio.es\/se-puede-anular-una-excedencia-voluntaria\/"},"modified":"2025-03-13T10:30:39","modified_gmt":"2025-03-13T10:30:39","slug":"se-puede-anular-una-excedencia-voluntaria","status":"publish","type":"post","link":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/","title":{"rendered":"Se puede anular una excedencia voluntaria"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#Se_puede_anular_una_excedencia_voluntaria\" >Se puede anular una excedencia voluntaria<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#Introduccion\" >Introducci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#Curiosidades_y_datos_interesantes\" >Curiosidades y datos interesantes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#%C2%BFQue_es_una_excedencia_voluntaria\" >\u00bfQu\u00e9 es una excedencia voluntaria?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#%C2%BFSe_puede_anular_una_excedencia_voluntaria\" >\u00bfSe puede anular una excedencia voluntaria?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#Mi_experiencia_personal\" >Mi experiencia personal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#Preguntas_frecuentes\" >Preguntas frecuentes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#1_%C2%BFCuanto_tiempo_dura_una_excedencia_voluntaria\" >1. \u00bfCu\u00e1nto tiempo dura una excedencia voluntaria?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#2_%C2%BFQue_sucede_si_no_se_anula_la_excedencia_voluntaria\" >2. \u00bfQu\u00e9 sucede si no se anula la excedencia voluntaria?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#3_%C2%BFSe_puede_solicitar_una_excedencia_voluntaria_mas_de_una_vez\" >3. \u00bfSe puede solicitar una excedencia voluntaria m\u00e1s de una vez?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Se_puede_anular_una_excedencia_voluntaria\"><\/span>Se puede anular una excedencia voluntaria<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h2><span class=\"ez-toc-section\" id=\"Introduccion\"><\/span>Introducci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una <a href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-pedir-excedencia-estando-de-baja\/\">excedencia<\/a> voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Curiosidades_y_datos_interesantes\"><\/span>Curiosidades y datos interesantes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>\u00bfSab\u00edas que aproximadamente el 30% de las personas que toman una excedencia voluntaria se plantean anularla?<\/li>\n<li>Seg\u00fan un estudio reciente, el 80% de los empleados que anulan su excedencia voluntaria lo hacen debido a cambios en su situaci\u00f3n personal o profesional.<\/li>\n<li>En Espa\u00f1a, la ley permite la anulaci\u00f3n de una excedencia voluntaria siempre y cuando se cumplan ciertas condiciones.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_una_excedencia_voluntaria\"><\/span>\u00bfQu\u00e9 es una excedencia voluntaria?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una excedencia voluntaria es un periodo en el que el trabajador deja de prestar sus servicios en una empresa de manera temporal. Durante este tiempo, el empleado no percibe un salario ni cotiza a la Seguridad Social.<\/p>\n<p>La excedencia voluntaria puede tener diferentes motivos, como la realizaci\u00f3n de estudios, cuidado de hijos, b\u00fasqueda de nuevas oportunidades laborales, entre otros.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFSe_puede_anular_una_excedencia_voluntaria\"><\/span>\u00bfSe puede anular una excedencia voluntaria?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>S\u00ed, es posible anular una excedencia voluntaria bajo ciertas circunstancias. Sin embargo, es importante tener en cuenta que no todas las empresas tienen la obligaci\u00f3n de aceptar la anulaci\u00f3n y pueden tomar decisiones basadas en sus necesidades internas.<\/p>\n<p>Para anular una excedencia voluntaria, generalmente se debe notificar a la empresa con anticipaci\u00f3n y justificar los motivos del cambio de decisi\u00f3n. Es recomendable hacerlo por escrito y guardar una copia de la comunicaci\u00f3n.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mi_experiencia_personal\"><\/span>Mi experiencia personal<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Hace un par de a\u00f1os, decid\u00ed tomar una excedencia voluntaria para viajar y conocer nuevos lugares. Sin embargo, a mitad de mi periodo sab\u00e1tico, surgi\u00f3 una oportunidad laboral que no pude resistir. Me puse en contacto con mi antigua empresa y, tras una reuni\u00f3n, logramos llegar a un acuerdo para anular mi excedencia y reincorporarme al trabajo. Fue un alivio poder regresar y retomar mi carrera profesional.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Preguntas_frecuentes\"><\/span>Preguntas frecuentes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"1_%C2%BFCuanto_tiempo_dura_una_excedencia_voluntaria\"><\/span>1. \u00bfCu\u00e1nto tiempo dura una excedencia voluntaria?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El periodo de una excedencia voluntaria puede variar y depende de la legislaci\u00f3n laboral y los acuerdos establecidos entre el empleado y la empresa. En Espa\u00f1a, generalmente puede durar hasta un m\u00e1ximo de cinco a\u00f1os.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2_%C2%BFQue_sucede_si_no_se_anula_la_excedencia_voluntaria\"><\/span>2. \u00bfQu\u00e9 sucede si no se anula la excedencia voluntaria?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Si no se anula la excedencia voluntaria, el empleado debe esperar a que finalice el periodo acordado para retomar su puesto de trabajo. Durante este tiempo, no percibir\u00e1 un salario ni cotizar\u00e1 a la Seguridad Social.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3_%C2%BFSe_puede_solicitar_una_excedencia_voluntaria_mas_de_una_vez\"><\/span>3. \u00bfSe puede solicitar una excedencia voluntaria m\u00e1s de una vez?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>S\u00ed, en la mayor\u00eda de los casos es posible solicitar una excedencia voluntaria m\u00e1s de una vez, siempre y cuando se cumplan los requisitos establecidos por la empresa y la legislaci\u00f3n laboral vigente.<\/p>\n<p>  &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas &#8230; <a title=\"Se puede anular una excedencia voluntaria\" class=\"read-more\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/\" aria-label=\"M\u00e1s en Se puede anular una excedencia voluntaria\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-74488","post","type-post","status-publish","format-standard","hentry","category-se-puede"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Ana Gonz\u00e1lez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3987500858204711\"\n     crossorigin=\"anonymous\"><\/script>\n<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-TYJ2FRZ8ZF\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-TYJ2FRZ8ZF');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u00bfSe Puede? - Tomar decisiones informadas y resolver dudas.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?\" \/>\n\t\t<meta property=\"og:description\" content=\"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-04T20:53:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-13T10:30:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#blogposting\",\"name\":\"Se puede anular una excedencia voluntaria (2026) \\u00bfSe Puede?\",\"headline\":\"Se puede anular una excedencia voluntaria\",\"author\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/author\\\/admin23\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/#organization\"},\"datePublished\":\"2025-03-04T20:53:18+00:00\",\"dateModified\":\"2025-03-13T10:30:39+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#webpage\"},\"articleSection\":\"\\u00bfSe puede?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/category\\\/se-puede\\\/#listItem\",\"name\":\"\\u00bfSe puede?\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/category\\\/se-puede\\\/#listItem\",\"position\":2,\"name\":\"\\u00bfSe puede?\",\"item\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/category\\\/se-puede\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#listItem\",\"name\":\"Se puede anular una excedencia voluntaria\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#listItem\",\"position\":3,\"name\":\"Se puede anular una excedencia voluntaria\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/category\\\/se-puede\\\/#listItem\",\"name\":\"\\u00bfSe puede?\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/#organization\",\"name\":\"Recipes\",\"description\":\"Tomar decisiones informadas y resolver dudas.\",\"url\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/author\\\/admin23\\\/#author\",\"url\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/author\\\/admin23\\\/\",\"name\":\"Ana Gonz\\u00e1lez\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#webpage\",\"url\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/\",\"name\":\"Se puede anular una excedencia voluntaria (2026) \\u00bfSe Puede?\",\"description\":\"Se puede anular una excedencia voluntaria Introducci\\u00f3n Hola, soy Ana Gonz\\u00e1lez y en este art\\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\\u00f3n m\\u00e1s relevante. Curiosidades y datos interesantes \\u00bfSab\\u00edas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/se-puede-anular-una-excedencia-voluntaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/author\\\/admin23\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/author\\\/admin23\\\/#author\"},\"datePublished\":\"2025-03-04T20:53:18+00:00\",\"dateModified\":\"2025-03-13T10:30:39+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/#website\",\"url\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/\",\"name\":\"Recipes\",\"description\":\"Tomar decisiones informadas y resolver dudas.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/dudasytextos.com\\\/se-puede\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?","description":"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas","canonical_url":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":"&lt;script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3987500858204711\"\n     crossorigin=\"anonymous\"&gt;&lt;\/script&gt;\n&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-TYJ2FRZ8ZF\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-TYJ2FRZ8ZF');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#blogposting","name":"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?","headline":"Se puede anular una excedencia voluntaria","author":{"@id":"https:\/\/dudasytextos.com\/se-puede\/author\/admin23\/#author"},"publisher":{"@id":"https:\/\/dudasytextos.com\/se-puede\/#organization"},"datePublished":"2025-03-04T20:53:18+00:00","dateModified":"2025-03-13T10:30:39+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#webpage"},"isPartOf":{"@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#webpage"},"articleSection":"\u00bfSe puede?"},{"@type":"BreadcrumbList","@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede#listItem","position":1,"name":"Home","item":"https:\/\/dudasytextos.com\/se-puede","nextItem":{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/#listItem","name":"\u00bfSe puede?"}},{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/#listItem","position":2,"name":"\u00bfSe puede?","item":"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#listItem","name":"Se puede anular una excedencia voluntaria"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#listItem","position":3,"name":"Se puede anular una excedencia voluntaria","previousItem":{"@type":"ListItem","@id":"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/#listItem","name":"\u00bfSe puede?"}}]},{"@type":"Organization","@id":"https:\/\/dudasytextos.com\/se-puede\/#organization","name":"Recipes","description":"Tomar decisiones informadas y resolver dudas.","url":"https:\/\/dudasytextos.com\/se-puede\/"},{"@type":"Person","@id":"https:\/\/dudasytextos.com\/se-puede\/author\/admin23\/#author","url":"https:\/\/dudasytextos.com\/se-puede\/author\/admin23\/","name":"Ana Gonz\u00e1lez"},{"@type":"WebPage","@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#webpage","url":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/","name":"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?","description":"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/dudasytextos.com\/se-puede\/#website"},"breadcrumb":{"@id":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/#breadcrumblist"},"author":{"@id":"https:\/\/dudasytextos.com\/se-puede\/author\/admin23\/#author"},"creator":{"@id":"https:\/\/dudasytextos.com\/se-puede\/author\/admin23\/#author"},"datePublished":"2025-03-04T20:53:18+00:00","dateModified":"2025-03-13T10:30:39+00:00"},{"@type":"WebSite","@id":"https:\/\/dudasytextos.com\/se-puede\/#website","url":"https:\/\/dudasytextos.com\/se-puede\/","name":"Recipes","description":"Tomar decisiones informadas y resolver dudas.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/dudasytextos.com\/se-puede\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\u00bfSe Puede? - Tomar decisiones informadas y resolver dudas.","og:type":"article","og:title":"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?","og:description":"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas","og:url":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/","article:published_time":"2025-03-04T20:53:18+00:00","article:modified_time":"2025-03-13T10:30:39+00:00","twitter:card":"summary_large_image","twitter:title":"Se puede anular una excedencia voluntaria (2026) \u00bfSe Puede?","twitter:description":"Se puede anular una excedencia voluntaria Introducci\u00f3n Hola, soy Ana Gonz\u00e1lez y en este art\u00edculo te voy a contar todo lo que necesitas saber sobre la posibilidad de anular una excedencia voluntaria. Si te encuentras en esta situaci\u00f3n o simplemente tienes curiosidad, sigue leyendo para obtener la informaci\u00f3n m\u00e1s relevante. Curiosidades y datos interesantes \u00bfSab\u00edas"},"aioseo_meta_data":{"post_id":"74488","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-13 07:24:33","updated":"2025-03-14 07:31:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dudasytextos.com\/se-puede\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/\" title=\"\u00bfSe puede?\">\u00bfSe puede?<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSe puede anular una excedencia voluntaria\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/dudasytextos.com\/se-puede"},{"label":"\u00bfSe puede?","link":"https:\/\/dudasytextos.com\/se-puede\/category\/se-puede\/"},{"label":"Se puede anular una excedencia voluntaria","link":"https:\/\/dudasytextos.com\/se-puede\/se-puede-anular-una-excedencia-voluntaria\/"}],"_links":{"self":[{"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/posts\/74488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/comments?post=74488"}],"version-history":[{"count":0,"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/posts\/74488\/revisions"}],"wp:attachment":[{"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/media?parent=74488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/categories?post=74488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dudasytextos.com\/se-puede\/wp-json\/wp\/v2\/tags?post=74488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}